{"id":219412,"date":"2016-04-13T04:12:26","date_gmt":"2016-04-13T04:12:26","guid":{"rendered":"http:\/\/blog.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Lamborghini_Egoista-6-1536.jpg"},"modified":"2016-05-19T03:44:21","modified_gmt":"2016-05-19T03:44:21","slug":"2013_lamborghini_egoista-6-1536","status":"inherit","type":"attachment","link":"https:\/\/www.supercars.net\/blog\/2013-lamborghini-egoista\/2013_lamborghini_egoista-6-1536\/","title":{"rendered":"2013 Lamborghini Egoista"},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-219412","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>2013 Lamborghini Egoista | | SuperCars.net<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Lamborghini_Egoista-6-1536.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"2013 Lamborghini Egoista | | SuperCars.net\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Lamborghini_Egoista-6-1536.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Supercars.net\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Supercars.net\/\" \/>\n<meta property=\"article:modified_time\" content=\"2016-05-19T03:44:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Lamborghini_Egoista-6-1536.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1536\" \/>\n\t<meta property=\"og:image:height\" content=\"1086\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@supercars_net\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/2013_Lamborghini_Egoista-6-1536.jpg\",\"url\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/2013_Lamborghini_Egoista-6-1536.jpg\",\"name\":\"2013 Lamborghini Egoista | | SuperCars.net\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/#website\"},\"datePublished\":\"2016-04-13T04:12:26+00:00\",\"dateModified\":\"2016-05-19T03:44:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/2013_Lamborghini_Egoista-6-1536.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.supercars.net\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/2013_Lamborghini_Egoista-6-1536.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/2013_Lamborghini_Egoista-6-1536.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"2013 Lamborghini Egoista\",\"item\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/2013-lamborghini-egoista\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"2013 Lamborghini Egoista\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/\",\"name\":\"Supercars.net\",\"description\":\"Exotic and Supercar news, information, pictures and videos\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"2013 Lamborghini Egoista | | SuperCars.net","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Lamborghini_Egoista-6-1536.jpg","og_locale":"en_US","og_type":"article","og_title":"2013 Lamborghini Egoista | | SuperCars.net","og_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Lamborghini_Egoista-6-1536.jpg","og_site_name":"Supercars.net","article_publisher":"https:\/\/www.facebook.com\/Supercars.net\/","article_modified_time":"2016-05-19T03:44:21+00:00","og_image":[{"width":1536,"height":1086,"url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Lamborghini_Egoista-6-1536.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@supercars_net","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Lamborghini_Egoista-6-1536.jpg","url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Lamborghini_Egoista-6-1536.jpg","name":"2013 Lamborghini Egoista | | SuperCars.net","isPartOf":{"@id":"https:\/\/www.supercars.net\/blog\/#website"},"datePublished":"2016-04-13T04:12:26+00:00","dateModified":"2016-05-19T03:44:21+00:00","breadcrumb":{"@id":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Lamborghini_Egoista-6-1536.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Lamborghini_Egoista-6-1536.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Lamborghini_Egoista-6-1536.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.supercars.net\/blog\/"},{"@type":"ListItem","position":2,"name":"2013 Lamborghini Egoista","item":"https:\/\/www.supercars.net\/blog\/2013-lamborghini-egoista\/"},{"@type":"ListItem","position":3,"name":"2013 Lamborghini Egoista"}]},{"@type":"WebSite","@id":"https:\/\/www.supercars.net\/blog\/#website","url":"https:\/\/www.supercars.net\/blog\/","name":"Supercars.net","description":"Exotic and Supercar news, information, pictures and videos","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.supercars.net\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"smush":{"stats":{"percent":17.73,"bytes":401252,"size_before":2262837,"size_after":1861585,"time":9.8,"api_version":"1.0","lossy":1,"keep_exif":0},"sizes":{"thumbnail":{"time":0.18,"bytes":412,"percent":10.6,"size_before":3888,"size_after":3476},"zeen-293-full":{"time":0.39,"bytes":3271,"percent":16.22,"size_before":20165,"size_after":16894},"zeen-370-490":{"time":0.67,"bytes":8749,"percent":18.65,"size_before":46918,"size_after":38169},"zeen-390-390":{"time":0.39,"bytes":7375,"percent":17.86,"size_before":41301,"size_after":33926},"zeen-770-513":{"time":0.61,"bytes":16642,"percent":18.25,"size_before":91200,"size_after":74558},"medium":{"time":0.14,"bytes":3460,"percent":16.39,"size_before":21111,"size_after":17651},"lets-review-360-240":{"time":0.48,"bytes":4589,"percent":16.98,"size_before":27023,"size_after":22434},"zeen-370-247":{"time":0.24,"bytes":4752,"percent":16.76,"size_before":28347,"size_after":23595},"zeen-585-293":{"time":0.14,"bytes":9227,"percent":18.55,"size_before":49751,"size_after":40524},"zeen-585-775":{"time":0.36,"bytes":20397,"percent":20.58,"size_before":99091,"size_after":78694},"medium_large":{"time":0.4,"bytes":17193,"percent":18.36,"size_before":93625,"size_after":76432},"zeen-293-293":{"time":0.36,"bytes":4642,"percent":17.51,"size_before":26509,"size_after":21867},"zeen-900-900":{"time":0.45,"bytes":34495,"percent":21.34,"size_before":161643,"size_after":127148},"zeen-585-585":{"time":0.51,"bytes":14834,"percent":18.65,"size_before":79547,"size_after":64713},"zeen-770-1020":{"time":0.23,"bytes":34816,"percent":22.4,"size_before":155439,"size_after":120623},"zeen-1500-750":{"time":0.35,"bytes":52393,"percent":22.84,"size_before":229397,"size_after":177004},"large":{"time":0.21,"bytes":26845,"percent":18.04,"size_before":148784,"size_after":121939},"post-thumbnail":{"time":0.71,"bytes":35721,"percent":20.11,"size_before":177634,"size_after":141913},"zeen-1170-585":{"time":0.86,"bytes":32343,"percent":21.05,"size_before":153614,"size_after":121271},"zeen-1400-full":{"time":0.48,"bytes":53276,"percent":21.41,"size_before":248894,"size_after":195618},"zeen-770-full":{"time":0.22,"bytes":3288,"percent":4.12,"size_before":79720,"size_after":76432},"zeen-1155-770":{"time":0.26,"bytes":6045,"percent":4.09,"size_before":147958,"size_after":141913},"gform-image-choice-sm":{"time":0.37,"bytes":1342,"percent":5.59,"size_before":24024,"size_after":22682},"gform-image-choice-md":{"time":0.46,"bytes":1847,"percent":5,"size_before":36911,"size_after":35064},"gform-image-choice-lg":{"time":0.33,"bytes":3298,"percent":4.69,"size_before":70343,"size_after":67045}},"webp_flag":"2016\/04\/2013_Lamborghini_Egoista-6-1536.jpg.webp"},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Lamborghini_Egoista-6-1536.jpg'><img decoding=\"async\" width=\"1536\" height=\"1086\" src=\"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Lamborghini_Egoista-6-1536.jpg\" class=\"attachment-medium size-full\" alt=\"2013 Lamborghini Egoista\" srcset=\"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Lamborghini_Egoista-6-1536-300x212.jpg 300w, https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Lamborghini_Egoista-6-1536-1024x724.jpg 1024w, https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Lamborghini_Egoista-6-1536-100x71.jpg 100w, https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Lamborghini_Egoista-6-1536-770x544.jpg 770w, https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Lamborghini_Egoista-6-1536-293x207.jpg 293w, https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Lamborghini_Egoista-6-1536-1400x990.jpg 1400w, https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Lamborghini_Egoista-6-1536.jpg 1536w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"2013 Lamborghini Egoista","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1536,"height":1086,"file":"2016\/04\/2013_Lamborghini_Egoista-6-1536.jpg","filesize":580064,"sizes":{"medium":{"file":"2013_Lamborghini_Egoista-6-1536-300x212.jpg","width":300,"height":212,"filesize":18709,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Lamborghini_Egoista-6-1536-300x212.jpg"},"large":{"file":"2013_Lamborghini_Egoista-6-1536-1024x724.jpg","width":1024,"height":724,"filesize":127210,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Lamborghini_Egoista-6-1536-1024x724.jpg"},"thumbnail":{"file":"2013_Lamborghini_Egoista-6-1536-100x71.jpg","width":100,"height":71,"filesize":3778,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Lamborghini_Egoista-6-1536-100x71.jpg"},"medium_large":{"file":"2013_Lamborghini_Egoista-6-1536-770x544.jpg","width":770,"height":544,"filesize":79817,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Lamborghini_Egoista-6-1536-770x544.jpg"},"lets-review-360-240":{"file":"2013_Lamborghini_Egoista-6-1536-360x240.jpg","width":360,"height":240,"filesize":23707,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Lamborghini_Egoista-6-1536-360x240.jpg"},"post-thumbnail":{"file":"2013_Lamborghini_Egoista-6-1536-1155x770.jpg","width":1155,"height":770,"filesize":147958,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Lamborghini_Egoista-6-1536-1155x770.jpg"},"zeen-370-247":{"file":"2013_Lamborghini_Egoista-6-1536-370x247.jpg","width":370,"height":247,"filesize":24886,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Lamborghini_Egoista-6-1536-370x247.jpg"},"zeen-585-293":{"file":"2013_Lamborghini_Egoista-6-1536-585x293.jpg","width":585,"height":293,"filesize":42696,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Lamborghini_Egoista-6-1536-585x293.jpg"},"zeen-770-513":{"file":"2013_Lamborghini_Egoista-6-1536-770x513.jpg","width":770,"height":513,"filesize":77896,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Lamborghini_Egoista-6-1536-770x513.jpg"},"zeen-1155-770":{"file":"2013_Lamborghini_Egoista-6-1536-1155x770.jpg","width":1155,"height":770,"filesize":147958,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Lamborghini_Egoista-6-1536-1155x770.jpg"},"zeen-1170-585":{"file":"2013_Lamborghini_Egoista-6-1536-1170x585.jpg","width":1170,"height":585,"filesize":126579,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Lamborghini_Egoista-6-1536-1170x585.jpg"},"zeen-1500-750":{"file":"2013_Lamborghini_Egoista-6-1536-1500x750.jpg","width":1500,"height":750,"filesize":183591,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Lamborghini_Egoista-6-1536-1500x750.jpg"},"zeen-293-293":{"file":"2013_Lamborghini_Egoista-6-1536-293x293.jpg","width":293,"height":293,"filesize":23162,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Lamborghini_Egoista-6-1536-293x293.jpg"},"zeen-390-390":{"file":"2013_Lamborghini_Egoista-6-1536-390x390.jpg","width":390,"height":390,"filesize":35730,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Lamborghini_Egoista-6-1536-390x390.jpg"},"zeen-585-585":{"file":"2013_Lamborghini_Egoista-6-1536-585x585.jpg","width":585,"height":585,"filesize":67832,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Lamborghini_Egoista-6-1536-585x585.jpg"},"zeen-900-900":{"file":"2013_Lamborghini_Egoista-6-1536-900x900.jpg","width":900,"height":900,"filesize":132662,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Lamborghini_Egoista-6-1536-900x900.jpg"},"zeen-370-490":{"file":"2013_Lamborghini_Egoista-6-1536-370x490.jpg","width":370,"height":490,"filesize":40099,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Lamborghini_Egoista-6-1536-370x490.jpg"},"zeen-585-775":{"file":"2013_Lamborghini_Egoista-6-1536-585x775.jpg","width":585,"height":775,"filesize":82389,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Lamborghini_Egoista-6-1536-585x775.jpg"},"zeen-770-1020":{"file":"2013_Lamborghini_Egoista-6-1536-770x1020.jpg","width":770,"height":1020,"filesize":125496,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Lamborghini_Egoista-6-1536-770x1020.jpg"},"zeen-293-full":{"file":"2013_Lamborghini_Egoista-6-1536-293x207.jpg","width":293,"height":207,"filesize":17896,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Lamborghini_Egoista-6-1536-293x207.jpg"},"zeen-770-full":{"file":"2013_Lamborghini_Egoista-6-1536-770x544.jpg","width":770,"height":544,"filesize":79720,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Lamborghini_Egoista-6-1536-770x544.jpg"},"zeen-1400-full":{"file":"2013_Lamborghini_Egoista-6-1536-1400x990.jpg","width":1400,"height":990,"filesize":203174,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Lamborghini_Egoista-6-1536-1400x990.jpg"},"gform-image-choice-sm":{"file":"2013_Lamborghini_Egoista-6-1536-300x300.jpg","width":300,"height":300,"filesize":24024,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Lamborghini_Egoista-6-1536-300x300.jpg"},"gform-image-choice-md":{"file":"2013_Lamborghini_Egoista-6-1536-400x400.jpg","width":400,"height":400,"filesize":36911,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Lamborghini_Egoista-6-1536-400x400.jpg"},"gform-image-choice-lg":{"file":"2013_Lamborghini_Egoista-6-1536-600x600.jpg","width":600,"height":600,"filesize":70343,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Lamborghini_Egoista-6-1536-600x600.jpg"},"full":{"file":"2013_Lamborghini_Egoista-6-1536.jpg","width":1536,"height":1086,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Lamborghini_Egoista-6-1536.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":219377,"source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Lamborghini_Egoista-6-1536.jpg","_links":{"self":[{"href":"https:\/\/www.supercars.net\/blog\/wp-json\/wp\/v2\/media\/219412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.supercars.net\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.supercars.net\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.supercars.net\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.supercars.net\/blog\/wp-json\/wp\/v2\/comments?post=219412"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":219377,"href":"https:\/\/www.supercars.net\/blog\/wp-json\/wp\/v2\/posts\/219377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}