{"id":244960,"date":"2016-04-16T11:39:42","date_gmt":"2016-04-16T11:39:42","guid":{"rendered":"http:\/\/blog.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/1978_Porsche_93578MobyDick-2-1024.jpg"},"modified":"2016-04-16T11:39:42","modified_gmt":"2016-04-16T11:39:42","slug":"1978_porsche_93578mobydick-2-1024","status":"inherit","type":"attachment","link":"https:\/\/www.supercars.net\/blog\/1978-porsche-93578-moby-dick\/1978_porsche_93578mobydick-2-1024\/","title":{"rendered":"1978_Porsche_93578MobyDick-2-1024"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-244960","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>1978_Porsche_93578MobyDick-2-1024 | | SuperCars.net<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/1978_Porsche_93578MobyDick-2-1024.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"1978_Porsche_93578MobyDick-2-1024 | | SuperCars.net\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/1978_Porsche_93578MobyDick-2-1024.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Supercars.net\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Supercars.net\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/1978_Porsche_93578MobyDick-2-1024.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@supercars_net\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/1978_Porsche_93578MobyDick-2-1024.jpg\",\"url\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/1978_Porsche_93578MobyDick-2-1024.jpg\",\"name\":\"1978_Porsche_93578MobyDick-2-1024 | | SuperCars.net\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/#website\"},\"datePublished\":\"2016-04-16T11:39:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/1978_Porsche_93578MobyDick-2-1024.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.supercars.net\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/1978_Porsche_93578MobyDick-2-1024.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/1978_Porsche_93578MobyDick-2-1024.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"1978 Porsche 935\\\/78 \u2018Moby Dick\u2019\",\"item\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/1978-porsche-93578-moby-dick\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"1978_Porsche_93578MobyDick-2-1024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/\",\"name\":\"Supercars.net\",\"description\":\"Exotic and Supercar news, information, pictures and videos\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"1978_Porsche_93578MobyDick-2-1024 | | SuperCars.net","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/1978_Porsche_93578MobyDick-2-1024.jpg","og_locale":"en_US","og_type":"article","og_title":"1978_Porsche_93578MobyDick-2-1024 | | SuperCars.net","og_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/1978_Porsche_93578MobyDick-2-1024.jpg","og_site_name":"Supercars.net","article_publisher":"https:\/\/www.facebook.com\/Supercars.net\/","og_image":[{"width":1024,"height":683,"url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/1978_Porsche_93578MobyDick-2-1024.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@supercars_net","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/1978_Porsche_93578MobyDick-2-1024.jpg","url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/1978_Porsche_93578MobyDick-2-1024.jpg","name":"1978_Porsche_93578MobyDick-2-1024 | | SuperCars.net","isPartOf":{"@id":"https:\/\/www.supercars.net\/blog\/#website"},"datePublished":"2016-04-16T11:39:42+00:00","breadcrumb":{"@id":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/1978_Porsche_93578MobyDick-2-1024.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/1978_Porsche_93578MobyDick-2-1024.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/1978_Porsche_93578MobyDick-2-1024.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.supercars.net\/blog\/"},{"@type":"ListItem","position":2,"name":"1978 Porsche 935\/78 \u2018Moby Dick\u2019","item":"https:\/\/www.supercars.net\/blog\/1978-porsche-93578-moby-dick\/"},{"@type":"ListItem","position":3,"name":"1978_Porsche_93578MobyDick-2-1024"}]},{"@type":"WebSite","@id":"https:\/\/www.supercars.net\/blog\/#website","url":"https:\/\/www.supercars.net\/blog\/","name":"Supercars.net","description":"Exotic and Supercar news, information, pictures and videos","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.supercars.net\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"smush":{"stats":{"percent":16.78,"bytes":166943,"size_before":994871,"size_after":827928,"time":7.090000000000001,"api_version":"1.0","lossy":1,"keep_exif":0},"sizes":{"thumbnail":{"time":0.53,"bytes":200,"percent":7.09,"size_before":2820,"size_after":2620},"zeen-293-full":{"time":0.17,"bytes":1698,"percent":11.49,"size_before":14776,"size_after":13078},"lets-review-360-240":{"time":0.18,"bytes":2606,"percent":12.8,"size_before":20358,"size_after":17752},"zeen-293-293":{"time":0.57,"bytes":2667,"percent":13.09,"size_before":20382,"size_after":17715},"medium":{"time":0.14,"bytes":1750,"percent":11.51,"size_before":15205,"size_after":13455},"zeen-370-247":{"time":0.15,"bytes":2701,"percent":12.45,"size_before":21687,"size_after":18986},"zeen-585-293":{"time":0.19,"bytes":5921,"percent":15.83,"size_before":37405,"size_after":31484},"zeen-390-390":{"time":0.25,"bytes":4703,"percent":14.65,"size_before":32104,"size_after":27401},"zeen-370-490":{"time":0.6,"bytes":5843,"percent":16.39,"size_before":35651,"size_after":29808},"zeen-770-513":{"time":0.81,"bytes":12597,"percent":17.57,"size_before":71681,"size_after":59084},"zeen-585-585":{"time":0.29,"bytes":12421,"percent":19.49,"size_before":63715,"size_after":51294},"medium_large":{"time":0.24,"bytes":12643,"percent":17.64,"size_before":71669,"size_after":59026},"zeen-770-1020":{"time":0.51,"bytes":23804,"percent":22.62,"size_before":105248,"size_after":81444},"zeen-1170-585":{"time":0.71,"bytes":26718,"percent":22.62,"size_before":118136,"size_after":91418},"zeen-585-775":{"time":0.18,"bytes":17956,"percent":22.38,"size_before":80243,"size_after":62287},"zeen-900-900":{"time":0.25,"bytes":27034,"percent":22.58,"size_before":119728,"size_after":92694},"gform-image-choice-sm":{"time":0.22,"bytes":711,"percent":3.71,"size_before":19152,"size_after":18441},"gform-image-choice-lg":{"time":0.21,"bytes":1867,"percent":3.41,"size_before":54811,"size_after":52944},"gform-image-choice-md":{"time":0.31,"bytes":1018,"percent":3.51,"size_before":28989,"size_after":27971},"zeen-770-full":{"time":0.58,"bytes":2085,"percent":3.41,"size_before":61111,"size_after":59026}},"webp_flag":"2016\/04\/1978_Porsche_93578MobyDick-2-1024.jpg.webp"},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/1978_Porsche_93578MobyDick-2-1024.jpg'><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/1978_Porsche_93578MobyDick-2-1024.jpg\" class=\"attachment-medium size-full\" alt=\"\" srcset=\"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/1978_Porsche_93578MobyDick-2-1024-300x200.jpg 300w, https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/1978_Porsche_93578MobyDick-2-1024-100x67.jpg 100w, https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/1978_Porsche_93578MobyDick-2-1024-770x514.jpg 770w, https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/1978_Porsche_93578MobyDick-2-1024-360x240.jpg 360w, https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/1978_Porsche_93578MobyDick-2-1024-370x247.jpg 370w, https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/1978_Porsche_93578MobyDick-2-1024-293x195.jpg 293w, https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/1978_Porsche_93578MobyDick-2-1024.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1024,"height":683,"file":"2016\/04\/1978_Porsche_93578MobyDick-2-1024.jpg","filesize":290080,"sizes":{"medium":{"file":"1978_Porsche_93578MobyDick-2-1024-300x200.jpg","width":300,"height":200,"filesize":14034,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/1978_Porsche_93578MobyDick-2-1024-300x200.jpg"},"thumbnail":{"file":"1978_Porsche_93578MobyDick-2-1024-100x67.jpg","width":100,"height":67,"filesize":2820,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/1978_Porsche_93578MobyDick-2-1024-100x67.jpg"},"medium_large":{"file":"1978_Porsche_93578MobyDick-2-1024-770x514.jpg","width":770,"height":514,"filesize":61175,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/1978_Porsche_93578MobyDick-2-1024-770x514.jpg"},"lets-review-360-240":{"file":"1978_Porsche_93578MobyDick-2-1024-360x240.jpg","width":360,"height":240,"filesize":18479,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/1978_Porsche_93578MobyDick-2-1024-360x240.jpg"},"zeen-370-247":{"file":"1978_Porsche_93578MobyDick-2-1024-370x247.jpg","width":370,"height":247,"filesize":19738,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/1978_Porsche_93578MobyDick-2-1024-370x247.jpg"},"zeen-585-293":{"file":"1978_Porsche_93578MobyDick-2-1024-585x293.jpg","width":585,"height":293,"filesize":32767,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/1978_Porsche_93578MobyDick-2-1024-585x293.jpg"},"zeen-770-513":{"file":"1978_Porsche_93578MobyDick-2-1024-770x513.jpg","width":770,"height":513,"filesize":61078,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/1978_Porsche_93578MobyDick-2-1024-770x513.jpg"},"zeen-1170-585":{"file":"1978_Porsche_93578MobyDick-2-1024-1024x585.jpg","width":1024,"height":585,"filesize":95539,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/1978_Porsche_93578MobyDick-2-1024-1024x585.jpg"},"zeen-293-293":{"file":"1978_Porsche_93578MobyDick-2-1024-293x293.jpg","width":293,"height":293,"filesize":18421,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/1978_Porsche_93578MobyDick-2-1024-293x293.jpg"},"zeen-390-390":{"file":"1978_Porsche_93578MobyDick-2-1024-390x390.jpg","width":390,"height":390,"filesize":28431,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/1978_Porsche_93578MobyDick-2-1024-390x390.jpg"},"zeen-585-585":{"file":"1978_Porsche_93578MobyDick-2-1024-585x585.jpg","width":585,"height":585,"filesize":53081,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/1978_Porsche_93578MobyDick-2-1024-585x585.jpg"},"zeen-900-900":{"file":"1978_Porsche_93578MobyDick-2-1024-900x683.jpg","width":900,"height":683,"filesize":97090,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/1978_Porsche_93578MobyDick-2-1024-900x683.jpg"},"zeen-370-490":{"file":"1978_Porsche_93578MobyDick-2-1024-370x490.jpg","width":370,"height":490,"filesize":30860,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/1978_Porsche_93578MobyDick-2-1024-370x490.jpg"},"zeen-585-775":{"file":"1978_Porsche_93578MobyDick-2-1024-585x683.jpg","width":585,"height":683,"filesize":65247,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/1978_Porsche_93578MobyDick-2-1024-585x683.jpg"},"zeen-770-1020":{"file":"1978_Porsche_93578MobyDick-2-1024-770x683.jpg","width":770,"height":683,"filesize":85288,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/1978_Porsche_93578MobyDick-2-1024-770x683.jpg"},"zeen-293-full":{"file":"1978_Porsche_93578MobyDick-2-1024-293x195.jpg","width":293,"height":195,"filesize":13648,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/1978_Porsche_93578MobyDick-2-1024-293x195.jpg"},"zeen-770-full":{"file":"1978_Porsche_93578MobyDick-2-1024-770x514.jpg","width":770,"height":514,"filesize":61111,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/1978_Porsche_93578MobyDick-2-1024-770x514.jpg"},"gform-image-choice-sm":{"file":"1978_Porsche_93578MobyDick-2-1024-300x300.jpg","width":300,"height":300,"filesize":19152,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/1978_Porsche_93578MobyDick-2-1024-300x300.jpg"},"gform-image-choice-md":{"file":"1978_Porsche_93578MobyDick-2-1024-400x400.jpg","width":400,"height":400,"filesize":28989,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/1978_Porsche_93578MobyDick-2-1024-400x400.jpg"},"gform-image-choice-lg":{"file":"1978_Porsche_93578MobyDick-2-1024-600x600.jpg","width":600,"height":600,"filesize":54811,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/1978_Porsche_93578MobyDick-2-1024-600x600.jpg"},"full":{"file":"1978_Porsche_93578MobyDick-2-1024.jpg","width":1024,"height":683,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/1978_Porsche_93578MobyDick-2-1024.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":244957,"source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/1978_Porsche_93578MobyDick-2-1024.jpg","_links":{"self":[{"href":"https:\/\/www.supercars.net\/blog\/wp-json\/wp\/v2\/media\/244960","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.supercars.net\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.supercars.net\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.supercars.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.supercars.net\/blog\/wp-json\/wp\/v2\/comments?post=244960"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":244957,"href":"https:\/\/www.supercars.net\/blog\/wp-json\/wp\/v2\/posts\/244957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}