{"id":246809,"date":"2016-04-16T18:50:37","date_gmt":"2016-04-16T18:50:37","guid":{"rendered":"http:\/\/blog.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Porsche_PanameraTurboExecutive-6-1024.jpg"},"modified":"2016-05-18T15:57:53","modified_gmt":"2016-05-18T15:57:53","slug":"panamera-turbo-executive-innenraum","status":"inherit","type":"attachment","link":"https:\/\/www.supercars.net\/blog\/2013-porsche-panamera-turbo-executive\/panamera-turbo-executive-innenraum\/","title":{"rendered":"2013 Porsche Panamera Turbo Executive"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-246809","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>2013 Porsche Panamera Turbo Executive | | SuperCars.net<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Porsche_PanameraTurboExecutive-6-1024.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"2013 Porsche Panamera Turbo Executive | | SuperCars.net\" \/>\n<meta property=\"og:description\" content=\"Panamera Turbo Executive - Innenraum\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Porsche_PanameraTurboExecutive-6-1024.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Supercars.net\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Supercars.net\/\" \/>\n<meta property=\"article:modified_time\" content=\"2016-05-18T15:57:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Porsche_PanameraTurboExecutive-6-1024.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@supercars_net\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/2013_Porsche_PanameraTurboExecutive-6-1024.jpg\",\"url\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/2013_Porsche_PanameraTurboExecutive-6-1024.jpg\",\"name\":\"2013 Porsche Panamera Turbo Executive | | SuperCars.net\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/#website\"},\"datePublished\":\"2016-04-16T18:50:37+00:00\",\"dateModified\":\"2016-05-18T15:57:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/2013_Porsche_PanameraTurboExecutive-6-1024.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.supercars.net\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/2013_Porsche_PanameraTurboExecutive-6-1024.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/2013_Porsche_PanameraTurboExecutive-6-1024.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"2013 Porsche Panamera Turbo Executive\",\"item\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/2013-porsche-panamera-turbo-executive\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"2013 Porsche Panamera Turbo Executive\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/\",\"name\":\"Supercars.net\",\"description\":\"Exotic and Supercar news, information, pictures and videos\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"2013 Porsche Panamera Turbo Executive | | SuperCars.net","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Porsche_PanameraTurboExecutive-6-1024.jpg","og_locale":"en_US","og_type":"article","og_title":"2013 Porsche Panamera Turbo Executive | | SuperCars.net","og_description":"Panamera Turbo Executive - Innenraum","og_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Porsche_PanameraTurboExecutive-6-1024.jpg","og_site_name":"Supercars.net","article_publisher":"https:\/\/www.facebook.com\/Supercars.net\/","article_modified_time":"2016-05-18T15:57:53+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Porsche_PanameraTurboExecutive-6-1024.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@supercars_net","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Porsche_PanameraTurboExecutive-6-1024.jpg","url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Porsche_PanameraTurboExecutive-6-1024.jpg","name":"2013 Porsche Panamera Turbo Executive | | SuperCars.net","isPartOf":{"@id":"https:\/\/www.supercars.net\/blog\/#website"},"datePublished":"2016-04-16T18:50:37+00:00","dateModified":"2016-05-18T15:57:53+00:00","breadcrumb":{"@id":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Porsche_PanameraTurboExecutive-6-1024.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Porsche_PanameraTurboExecutive-6-1024.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Porsche_PanameraTurboExecutive-6-1024.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.supercars.net\/blog\/"},{"@type":"ListItem","position":2,"name":"2013 Porsche Panamera Turbo Executive","item":"https:\/\/www.supercars.net\/blog\/2013-porsche-panamera-turbo-executive\/"},{"@type":"ListItem","position":3,"name":"2013 Porsche Panamera Turbo Executive"}]},{"@type":"WebSite","@id":"https:\/\/www.supercars.net\/blog\/#website","url":"https:\/\/www.supercars.net\/blog\/","name":"Supercars.net","description":"Exotic and Supercar news, information, pictures and videos","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.supercars.net\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"smush":{"stats":{"percent":9.57,"bytes":105703,"size_before":1104758,"size_after":999055,"time":6.420000000000001,"api_version":"1.0","lossy":1,"keep_exif":0},"sizes":{"thumbnail":{"time":0.1,"bytes":226,"percent":7.1,"size_before":3181,"size_after":2955},"zeen-293-293":{"time":0.26,"bytes":1406,"percent":7.63,"size_before":18428,"size_after":17022},"zeen-293-full":{"time":0.24,"bytes":1194,"percent":7.81,"size_before":15289,"size_after":14095},"medium":{"time":0.54,"bytes":1239,"percent":7.73,"size_before":16022,"size_after":14783},"zeen-390-390":{"time":0.32,"bytes":2170,"percent":7.66,"size_before":28344,"size_after":26174},"lets-review-360-240":{"time":0.17,"bytes":1643,"percent":8.42,"size_before":19524,"size_after":17881},"zeen-370-490":{"time":0.29,"bytes":2981,"percent":9.19,"size_before":32452,"size_after":29471},"zeen-585-293":{"time":0.17,"bytes":3337,"percent":9.23,"size_before":36148,"size_after":32811},"zeen-585-585":{"time":0.48,"bytes":5333,"percent":9.58,"size_before":55684,"size_after":50351},"zeen-900-900":{"time":0.18,"bytes":13769,"percent":11.46,"size_before":120182,"size_after":106413},"zeen-370-247":{"time":0.53,"bytes":1747,"percent":8.44,"size_before":20691,"size_after":18944},"zeen-1170-585":{"time":0.62,"bytes":13838,"percent":11.69,"size_before":118328,"size_after":104490},"zeen-770-513":{"time":0.26,"bytes":6137,"percent":9.2,"size_before":66685,"size_after":60548},"zeen-1500-750":{"time":0.27,"bytes":16282,"percent":12.17,"size_before":133838,"size_after":117556},"zeen-770-1020":{"time":0.18,"bytes":12055,"percent":11.58,"size_before":104066,"size_after":92011},"zeen-585-775":{"time":0.3,"bytes":9296,"percent":11.91,"size_before":78024,"size_after":68728},"medium_large":{"time":0.44,"bytes":6463,"percent":9.15,"size_before":70630,"size_after":64167},"gform-image-choice-md":{"time":0.21,"bytes":930,"percent":3.32,"size_before":27978,"size_after":27048},"zeen-770-full":{"time":0.21,"bytes":2720,"percent":4.07,"size_before":66887,"size_after":64167},"gform-image-choice-lg":{"time":0.31,"bytes":2300,"percent":4.24,"size_before":54222,"size_after":51922},"gform-image-choice-sm":{"time":0.34,"bytes":637,"percent":3.51,"size_before":18155,"size_after":17518}},"webp_flag":"2016\/04\/2013_Porsche_PanameraTurboExecutive-6-1024.jpg.webp"},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Porsche_PanameraTurboExecutive-6-1024.jpg'><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Porsche_PanameraTurboExecutive-6-1024.jpg\" class=\"attachment-medium size-full\" alt=\"2013 Porsche Panamera Turbo Executive\" srcset=\"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Porsche_PanameraTurboExecutive-6-1024-300x225.jpg 300w, https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Porsche_PanameraTurboExecutive-6-1024-100x75.jpg 100w, https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Porsche_PanameraTurboExecutive-6-1024-770x578.jpg 770w, https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Porsche_PanameraTurboExecutive-6-1024-293x220.jpg 293w, https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Porsche_PanameraTurboExecutive-6-1024.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Panamera Turbo Executive &#8211; Innenraum<\/p>\n"},"alt_text":"2013 Porsche Panamera Turbo Executive","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1024,"height":768,"file":"2016\/04\/2013_Porsche_PanameraTurboExecutive-6-1024.jpg","filesize":240885,"sizes":{"medium":{"file":"2013_Porsche_PanameraTurboExecutive-6-1024-300x225.jpg","width":300,"height":225,"filesize":15373,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Porsche_PanameraTurboExecutive-6-1024-300x225.jpg"},"thumbnail":{"file":"2013_Porsche_PanameraTurboExecutive-6-1024-100x75.jpg","width":100,"height":75,"filesize":3181,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Porsche_PanameraTurboExecutive-6-1024-100x75.jpg"},"medium_large":{"file":"2013_Porsche_PanameraTurboExecutive-6-1024-770x578.jpg","width":770,"height":578,"filesize":66881,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Porsche_PanameraTurboExecutive-6-1024-770x578.jpg"},"lets-review-360-240":{"file":"2013_Porsche_PanameraTurboExecutive-6-1024-360x240.jpg","width":360,"height":240,"filesize":18615,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Porsche_PanameraTurboExecutive-6-1024-360x240.jpg"},"zeen-370-247":{"file":"2013_Porsche_PanameraTurboExecutive-6-1024-370x247.jpg","width":370,"height":247,"filesize":19720,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Porsche_PanameraTurboExecutive-6-1024-370x247.jpg"},"zeen-585-293":{"file":"2013_Porsche_PanameraTurboExecutive-6-1024-585x293.jpg","width":585,"height":293,"filesize":34347,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Porsche_PanameraTurboExecutive-6-1024-585x293.jpg"},"zeen-770-513":{"file":"2013_Porsche_PanameraTurboExecutive-6-1024-770x513.jpg","width":770,"height":513,"filesize":63236,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Porsche_PanameraTurboExecutive-6-1024-770x513.jpg"},"zeen-1170-585":{"file":"2013_Porsche_PanameraTurboExecutive-6-1024-1024x585.jpg","width":1024,"height":585,"filesize":109102,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Porsche_PanameraTurboExecutive-6-1024-1024x585.jpg"},"zeen-1500-750":{"file":"2013_Porsche_PanameraTurboExecutive-6-1024-1024x750.jpg","width":1024,"height":750,"filesize":122880,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Porsche_PanameraTurboExecutive-6-1024-1024x750.jpg"},"zeen-293-293":{"file":"2013_Porsche_PanameraTurboExecutive-6-1024-293x293.jpg","width":293,"height":293,"filesize":17666,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Porsche_PanameraTurboExecutive-6-1024-293x293.jpg"},"zeen-390-390":{"file":"2013_Porsche_PanameraTurboExecutive-6-1024-390x390.jpg","width":390,"height":390,"filesize":27156,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Porsche_PanameraTurboExecutive-6-1024-390x390.jpg"},"zeen-585-585":{"file":"2013_Porsche_PanameraTurboExecutive-6-1024-585x585.jpg","width":585,"height":585,"filesize":52680,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Porsche_PanameraTurboExecutive-6-1024-585x585.jpg"},"zeen-900-900":{"file":"2013_Porsche_PanameraTurboExecutive-6-1024-900x768.jpg","width":900,"height":768,"filesize":111374,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Porsche_PanameraTurboExecutive-6-1024-900x768.jpg"},"zeen-370-490":{"file":"2013_Porsche_PanameraTurboExecutive-6-1024-370x490.jpg","width":370,"height":490,"filesize":30636,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Porsche_PanameraTurboExecutive-6-1024-370x490.jpg"},"zeen-585-775":{"file":"2013_Porsche_PanameraTurboExecutive-6-1024-585x768.jpg","width":585,"height":768,"filesize":71944,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Porsche_PanameraTurboExecutive-6-1024-585x768.jpg"},"zeen-770-1020":{"file":"2013_Porsche_PanameraTurboExecutive-6-1024-770x768.jpg","width":770,"height":768,"filesize":96367,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Porsche_PanameraTurboExecutive-6-1024-770x768.jpg"},"zeen-293-full":{"file":"2013_Porsche_PanameraTurboExecutive-6-1024-293x220.jpg","width":293,"height":220,"filesize":14652,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Porsche_PanameraTurboExecutive-6-1024-293x220.jpg"},"zeen-770-full":{"file":"2013_Porsche_PanameraTurboExecutive-6-1024-770x578.jpg","width":770,"height":578,"filesize":66887,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Porsche_PanameraTurboExecutive-6-1024-770x578.jpg"},"gform-image-choice-sm":{"file":"2013_Porsche_PanameraTurboExecutive-6-1024-300x300.jpg","width":300,"height":300,"filesize":18155,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Porsche_PanameraTurboExecutive-6-1024-300x300.jpg"},"gform-image-choice-md":{"file":"2013_Porsche_PanameraTurboExecutive-6-1024-400x400.jpg","width":400,"height":400,"filesize":27978,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Porsche_PanameraTurboExecutive-6-1024-400x400.jpg"},"gform-image-choice-lg":{"file":"2013_Porsche_PanameraTurboExecutive-6-1024-600x600.jpg","width":600,"height":600,"filesize":54222,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Porsche_PanameraTurboExecutive-6-1024-600x600.jpg"},"full":{"file":"2013_Porsche_PanameraTurboExecutive-6-1024.jpg","width":1024,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Porsche_PanameraTurboExecutive-6-1024.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":246798,"source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/04\/2013_Porsche_PanameraTurboExecutive-6-1024.jpg","_links":{"self":[{"href":"https:\/\/www.supercars.net\/blog\/wp-json\/wp\/v2\/media\/246809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.supercars.net\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.supercars.net\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.supercars.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.supercars.net\/blog\/wp-json\/wp\/v2\/comments?post=246809"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":246798,"href":"https:\/\/www.supercars.net\/blog\/wp-json\/wp\/v2\/posts\/246798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}