{"id":360291,"date":"2020-03-03T17:22:27","date_gmt":"2020-03-03T17:22:27","guid":{"rendered":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/03\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop.jpg"},"modified":"2020-03-03T17:30:47","modified_gmt":"2020-03-03T17:30:47","slug":"1968_plymouth_road_runner_426_hemi_hardtop","status":"inherit","type":"attachment","link":"https:\/\/www.supercars.net\/blog\/sixties-muscle-cars\/1968_plymouth_road_runner_426_hemi_hardtop\/","title":{"rendered":"1968 Plymouth Road Runner 426 Hemi Hardtop"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-360291","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>1968 Plymouth Road Runner 426 Hemi Hardtop | | SuperCars.net<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/03\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-scaled.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"1968 Plymouth Road Runner 426 Hemi Hardtop | | SuperCars.net\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/03\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-scaled.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Supercars.net\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Supercars.net\/\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-03T17:30:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/03\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1609\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@supercars_net\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-scaled.jpg\",\"url\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-scaled.jpg\",\"name\":\"1968 Plymouth Road Runner 426 Hemi Hardtop | | SuperCars.net\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/#website\"},\"datePublished\":\"2020-03-03T17:22:27+00:00\",\"dateModified\":\"2020-03-03T17:30:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-scaled.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.supercars.net\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-scaled.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-scaled.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"1960s Muscle Cars &#8211; Their Beginning, Downfall &#038; The Best Muscle Cars Ever Made\",\"item\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/sixties-muscle-cars\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"1968 Plymouth Road Runner 426 Hemi Hardtop\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/\",\"name\":\"Supercars.net\",\"description\":\"Exotic and Supercar news, information, pictures and videos\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"1968 Plymouth Road Runner 426 Hemi Hardtop | | SuperCars.net","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/03\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-scaled.jpg","og_locale":"en_US","og_type":"article","og_title":"1968 Plymouth Road Runner 426 Hemi Hardtop | | SuperCars.net","og_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/03\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-scaled.jpg","og_site_name":"Supercars.net","article_publisher":"https:\/\/www.facebook.com\/Supercars.net\/","article_modified_time":"2020-03-03T17:30:47+00:00","og_image":[{"width":2560,"height":1609,"url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/03\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@supercars_net","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/03\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-scaled.jpg","url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/03\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-scaled.jpg","name":"1968 Plymouth Road Runner 426 Hemi Hardtop | | SuperCars.net","isPartOf":{"@id":"https:\/\/www.supercars.net\/blog\/#website"},"datePublished":"2020-03-03T17:22:27+00:00","dateModified":"2020-03-03T17:30:47+00:00","breadcrumb":{"@id":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/03\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-scaled.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/03\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-scaled.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/03\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-scaled.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.supercars.net\/blog\/"},{"@type":"ListItem","position":2,"name":"1960s Muscle Cars &#8211; Their Beginning, Downfall &#038; The Best Muscle Cars Ever Made","item":"https:\/\/www.supercars.net\/blog\/sixties-muscle-cars\/"},{"@type":"ListItem","position":3,"name":"1968 Plymouth Road Runner 426 Hemi Hardtop"}]},{"@type":"WebSite","@id":"https:\/\/www.supercars.net\/blog\/#website","url":"https:\/\/www.supercars.net\/blog\/","name":"Supercars.net","description":"Exotic and Supercar news, information, pictures and videos","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.supercars.net\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"smush":{"stats":{"percent":4.62,"bytes":150770,"size_before":3265394,"size_after":3114624,"time":8.549999999999999,"api_version":"1.0","lossy":1,"keep_exif":0},"sizes":{"thumbnail":{"time":0.17,"bytes":223,"percent":7.44,"size_before":2998,"size_after":2775},"zeen-293-full":{"time":0.21,"bytes":911,"percent":5.78,"size_before":15763,"size_after":14852},"lets-review-360-240":{"time":0.18,"bytes":1214,"percent":5.31,"size_before":22848,"size_after":21634},"zeen-390-390":{"time":0.17,"bytes":1673,"percent":4.77,"size_before":35089,"size_after":33416},"zeen-585-293":{"time":0.22,"bytes":1958,"percent":4.82,"size_before":40626,"size_after":38668},"medium":{"time":0.18,"bytes":937,"percent":5.73,"size_before":16352,"size_after":15415},"zeen-293-293":{"time":0.18,"bytes":1128,"percent":5.16,"size_before":21878,"size_after":20750},"zeen-585-585":{"time":0.22,"bytes":3204,"percent":4.63,"size_before":69228,"size_after":66024},"medium_large":{"time":0.3,"bytes":3620,"percent":4.62,"size_before":78429,"size_after":74809},"zeen-370-490":{"time":0.18,"bytes":1857,"percent":4.7,"size_before":39552,"size_after":37695},"zeen-370-247":{"time":0.36,"bytes":1281,"percent":5.31,"size_before":24120,"size_after":22839},"zeen-770-513":{"time":0.34,"bytes":3712,"percent":4.53,"size_before":81903,"size_after":78191},"zeen-585-775":{"time":0.28,"bytes":3880,"percent":4.58,"size_before":84669,"size_after":80789},"zeen-1170-585":{"time":0.32,"bytes":5979,"percent":4.63,"size_before":129229,"size_after":123250},"zeen-770-1020":{"time":0.38,"bytes":6163,"percent":4.57,"size_before":134937,"size_after":128774},"post-thumbnail":{"time":0.38,"bytes":7427,"percent":4.59,"size_before":161684,"size_after":154257},"zeen-1500-750":{"time":0.42,"bytes":10459,"percent":5.09,"size_before":205434,"size_after":194975},"large":{"time":0.31,"bytes":5630,"percent":4.5,"size_before":125239,"size_after":119609},"1536x1536":{"time":0.36,"bytes":11186,"percent":4.51,"size_before":247946,"size_after":236760},"zeen-1400-full":{"time":0.66,"bytes":9592,"percent":4.53,"size_before":211666,"size_after":202074},"zeen-900-900":{"time":0.31,"bytes":6544,"percent":4.58,"size_before":143035,"size_after":136491},"2048x2048":{"time":0.4,"bytes":18906,"percent":4.65,"size_before":406878,"size_after":387972},"wp_scaled":{"time":0.78,"bytes":26001,"percent":4.37,"size_before":594707,"size_after":568706},"gform-image-choice-sm":{"time":0.19,"bytes":1129,"percent":4.97,"size_before":22730,"size_after":21601},"zeen-1155-770":{"time":0.33,"bytes":7427,"percent":4.59,"size_before":161684,"size_after":154257},"zeen-770-full":{"time":0.25,"bytes":3620,"percent":4.62,"size_before":78429,"size_after":74809},"gform-image-choice-md":{"time":0.22,"bytes":1743,"percent":4.8,"size_before":36328,"size_after":34585},"gform-image-choice-lg":{"time":0.25,"bytes":3366,"percent":4.67,"size_before":72013,"size_after":68647}},"webp_flag":"2020\/03\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-scaled.jpg.webp"},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/03\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-scaled.jpg'><img decoding=\"async\" width=\"3000\" height=\"1885\" src=\"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/03\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop.jpg\" class=\"attachment-medium size-full\" alt=\"1968 Plymouth Road Runner 426 Hemi Hardtop\" srcset=\"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/03\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-300x189.jpg 300w, https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/03\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-1024x643.jpg 1024w, https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/03\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-100x63.jpg 100w, https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/03\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-770x484.jpg 770w, https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/03\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-1536x965.jpg 1536w, https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/03\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-2048x1287.jpg 2048w, https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/03\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-293x184.jpg 293w, https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/03\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-1400x880.jpg 1400w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"1968 Plymouth Road Runner 426 Hemi Hardtop","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2560,"height":1609,"file":"2020\/03\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-scaled.jpg","filesize":594707,"sizes":{"medium":{"file":"1968_Plymouth_Road_Runner_426_Hemi_Hardtop-300x189.jpg","width":300,"height":189,"filesize":16352,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/03\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-300x189.jpg"},"large":{"file":"1968_Plymouth_Road_Runner_426_Hemi_Hardtop-1024x643.jpg","width":1024,"height":643,"filesize":125239,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/03\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-1024x643.jpg"},"thumbnail":{"file":"1968_Plymouth_Road_Runner_426_Hemi_Hardtop-100x63.jpg","width":100,"height":63,"filesize":2998,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/03\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-100x63.jpg"},"medium_large":{"file":"1968_Plymouth_Road_Runner_426_Hemi_Hardtop-770x484.jpg","width":770,"height":484,"filesize":78478,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/03\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-770x484.jpg"},"1536x1536":{"file":"1968_Plymouth_Road_Runner_426_Hemi_Hardtop-1536x965.jpg","width":1536,"height":965,"filesize":247946,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/03\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-1536x965.jpg"},"2048x2048":{"file":"1968_Plymouth_Road_Runner_426_Hemi_Hardtop-2048x1287.jpg","width":2048,"height":1287,"filesize":406878,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/03\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-2048x1287.jpg"},"lets-review-360-240":{"file":"1968_Plymouth_Road_Runner_426_Hemi_Hardtop-360x240.jpg","width":360,"height":240,"filesize":22848,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/03\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-360x240.jpg"},"post-thumbnail":{"file":"1968_Plymouth_Road_Runner_426_Hemi_Hardtop-1155x770.jpg","width":1155,"height":770,"filesize":161684,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/03\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-1155x770.jpg"},"zeen-370-247":{"file":"1968_Plymouth_Road_Runner_426_Hemi_Hardtop-370x247.jpg","width":370,"height":247,"filesize":24120,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/03\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-370x247.jpg"},"zeen-585-293":{"file":"1968_Plymouth_Road_Runner_426_Hemi_Hardtop-585x293.jpg","width":585,"height":293,"filesize":40626,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/03\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-585x293.jpg"},"zeen-770-513":{"file":"1968_Plymouth_Road_Runner_426_Hemi_Hardtop-770x513.jpg","width":770,"height":513,"filesize":81903,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/03\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-770x513.jpg"},"zeen-1155-770":{"file":"1968_Plymouth_Road_Runner_426_Hemi_Hardtop-1155x770.jpg","width":1155,"height":770,"filesize":161684,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/03\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-1155x770.jpg"},"zeen-1170-585":{"file":"1968_Plymouth_Road_Runner_426_Hemi_Hardtop-1170x585.jpg","width":1170,"height":585,"filesize":129229,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/03\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-1170x585.jpg"},"zeen-1500-750":{"file":"1968_Plymouth_Road_Runner_426_Hemi_Hardtop-1500x750.jpg","width":1500,"height":750,"filesize":205434,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/03\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-1500x750.jpg"},"zeen-293-293":{"file":"1968_Plymouth_Road_Runner_426_Hemi_Hardtop-293x293.jpg","width":293,"height":293,"filesize":21878,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/03\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-293x293.jpg"},"zeen-390-390":{"file":"1968_Plymouth_Road_Runner_426_Hemi_Hardtop-390x390.jpg","width":390,"height":390,"filesize":35089,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/03\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-390x390.jpg"},"zeen-585-585":{"file":"1968_Plymouth_Road_Runner_426_Hemi_Hardtop-585x585.jpg","width":585,"height":585,"filesize":69228,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/03\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-585x585.jpg"},"zeen-900-900":{"file":"1968_Plymouth_Road_Runner_426_Hemi_Hardtop-900x900.jpg","width":900,"height":900,"filesize":143035,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/03\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-900x900.jpg"},"zeen-370-490":{"file":"1968_Plymouth_Road_Runner_426_Hemi_Hardtop-370x490.jpg","width":370,"height":490,"filesize":39552,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/03\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-370x490.jpg"},"zeen-585-775":{"file":"1968_Plymouth_Road_Runner_426_Hemi_Hardtop-585x775.jpg","width":585,"height":775,"filesize":84669,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/03\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-585x775.jpg"},"zeen-770-1020":{"file":"1968_Plymouth_Road_Runner_426_Hemi_Hardtop-770x1020.jpg","width":770,"height":1020,"filesize":134937,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/03\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-770x1020.jpg"},"zeen-293-full":{"file":"1968_Plymouth_Road_Runner_426_Hemi_Hardtop-293x184.jpg","width":293,"height":184,"filesize":15763,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/03\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-293x184.jpg"},"zeen-770-full":{"file":"1968_Plymouth_Road_Runner_426_Hemi_Hardtop-770x484.jpg","width":770,"height":484,"filesize":78429,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/03\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-770x484.jpg"},"zeen-1400-full":{"file":"1968_Plymouth_Road_Runner_426_Hemi_Hardtop-1400x880.jpg","width":1400,"height":880,"filesize":211666,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/03\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-1400x880.jpg"},"gform-image-choice-sm":{"file":"1968_Plymouth_Road_Runner_426_Hemi_Hardtop-300x300.jpg","width":300,"height":300,"filesize":22730,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/03\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-300x300.jpg"},"gform-image-choice-md":{"file":"1968_Plymouth_Road_Runner_426_Hemi_Hardtop-400x400.jpg","width":400,"height":400,"filesize":36328,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/03\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-400x400.jpg"},"gform-image-choice-lg":{"file":"1968_Plymouth_Road_Runner_426_Hemi_Hardtop-600x600.jpg","width":600,"height":600,"filesize":72013,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/03\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-600x600.jpg"},"full":{"file":"1968_Plymouth_Road_Runner_426_Hemi_Hardtop-scaled.jpg","width":2560,"height":1609,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/03\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-scaled.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"original_image":"1968_Plymouth_Road_Runner_426_Hemi_Hardtop.jpg"},"post":359739,"source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/03\/1968_Plymouth_Road_Runner_426_Hemi_Hardtop-scaled.jpg","filename":"1968_Plymouth_Road_Runner_426_Hemi_Hardtop.jpg","filesize":594707,"_links":{"self":[{"href":"https:\/\/www.supercars.net\/blog\/wp-json\/wp\/v2\/media\/360291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.supercars.net\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.supercars.net\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.supercars.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.supercars.net\/blog\/wp-json\/wp\/v2\/comments?post=360291"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":359739,"href":"https:\/\/www.supercars.net\/blog\/wp-json\/wp\/v2\/posts\/359739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}