{"id":362382,"date":"2020-04-22T01:43:54","date_gmt":"2020-04-22T01:43:54","guid":{"rendered":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/04\/1995-Porsche-911-Speedster-993.jpg"},"modified":"2020-04-22T01:44:29","modified_gmt":"2020-04-22T01:44:29","slug":"1995-porsche-911-speedster-993","status":"inherit","type":"attachment","link":"https:\/\/www.supercars.net\/blog\/ultimate-guide-to-the-porsche-speedster\/1995-porsche-911-speedster-993\/","title":{"rendered":"1995 Porsche 911 Speedster (993)"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-362382","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>1995 Porsche 911 Speedster (993) | | SuperCars.net<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/04\/1995-Porsche-911-Speedster-993.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"1995 Porsche 911 Speedster (993) | | SuperCars.net\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/04\/1995-Porsche-911-Speedster-993.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Supercars.net\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Supercars.net\/\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-22T01:44:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/04\/1995-Porsche-911-Speedster-993.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1127\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@supercars_net\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/1995-Porsche-911-Speedster-993.jpg\",\"url\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/1995-Porsche-911-Speedster-993.jpg\",\"name\":\"1995 Porsche 911 Speedster (993) | | SuperCars.net\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/#website\"},\"datePublished\":\"2020-04-22T01:43:54+00:00\",\"dateModified\":\"2020-04-22T01:44:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/1995-Porsche-911-Speedster-993.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.supercars.net\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/1995-Porsche-911-Speedster-993.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/1995-Porsche-911-Speedster-993.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ultimate Guide to the Porsche Speedster\",\"item\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/ultimate-guide-to-the-porsche-speedster\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"1995 Porsche 911 Speedster (993)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/\",\"name\":\"Supercars.net\",\"description\":\"Exotic and Supercar news, information, pictures and videos\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"1995 Porsche 911 Speedster (993) | | SuperCars.net","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/04\/1995-Porsche-911-Speedster-993.jpg","og_locale":"en_US","og_type":"article","og_title":"1995 Porsche 911 Speedster (993) | | SuperCars.net","og_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/04\/1995-Porsche-911-Speedster-993.jpg","og_site_name":"Supercars.net","article_publisher":"https:\/\/www.facebook.com\/Supercars.net\/","article_modified_time":"2020-04-22T01:44:29+00:00","og_image":[{"width":2000,"height":1127,"url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/04\/1995-Porsche-911-Speedster-993.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@supercars_net","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/04\/1995-Porsche-911-Speedster-993.jpg","url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/04\/1995-Porsche-911-Speedster-993.jpg","name":"1995 Porsche 911 Speedster (993) | | SuperCars.net","isPartOf":{"@id":"https:\/\/www.supercars.net\/blog\/#website"},"datePublished":"2020-04-22T01:43:54+00:00","dateModified":"2020-04-22T01:44:29+00:00","breadcrumb":{"@id":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/04\/1995-Porsche-911-Speedster-993.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/04\/1995-Porsche-911-Speedster-993.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/04\/1995-Porsche-911-Speedster-993.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.supercars.net\/blog\/"},{"@type":"ListItem","position":2,"name":"Ultimate Guide to the Porsche Speedster","item":"https:\/\/www.supercars.net\/blog\/ultimate-guide-to-the-porsche-speedster\/"},{"@type":"ListItem","position":3,"name":"1995 Porsche 911 Speedster (993)"}]},{"@type":"WebSite","@id":"https:\/\/www.supercars.net\/blog\/#website","url":"https:\/\/www.supercars.net\/blog\/","name":"Supercars.net","description":"Exotic and Supercar news, information, pictures and videos","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.supercars.net\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"smush":{"stats":{"percent":15.61,"bytes":412486,"size_before":2642701,"size_after":2230215,"time":8.16,"api_version":"1.0","lossy":1,"keep_exif":0},"sizes":{"thumbnail":{"time":0.22,"bytes":752,"percent":24.18,"size_before":3110,"size_after":2358},"medium":{"time":0.12,"bytes":2184,"percent":13.32,"size_before":16398,"size_after":14214},"zeen-293-full":{"time":0.13,"bytes":2097,"percent":13.38,"size_before":15677,"size_after":13580},"zeen-370-247":{"time":0.17,"bytes":3465,"percent":12.83,"size_before":27004,"size_after":23539},"zeen-585-293":{"time":0.37,"bytes":6281,"percent":13.11,"size_before":47917,"size_after":41636},"lets-review-360-240":{"time":0.12,"bytes":3313,"percent":13.11,"size_before":25263,"size_after":21950},"zeen-390-390":{"time":0.17,"bytes":5557,"percent":13.89,"size_before":39998,"size_after":34441},"zeen-370-490":{"time":0.2,"bytes":6441,"percent":14.81,"size_before":43491,"size_after":37050},"zeen-293-293":{"time":0.3,"bytes":3168,"percent":13.09,"size_before":24210,"size_after":21042},"medium_large":{"time":0.29,"bytes":12762,"percent":14.51,"size_before":87982,"size_after":75220},"zeen-770-513":{"time":0.26,"bytes":15292,"percent":15.34,"size_before":99670,"size_after":84378},"zeen-585-775":{"time":0.26,"bytes":18202,"percent":18.61,"size_before":97826,"size_after":79624},"zeen-770-1020":{"time":0.25,"bytes":30320,"percent":19.64,"size_before":154394,"size_after":124074},"zeen-585-585":{"time":0.21,"bytes":13626,"percent":16.54,"size_before":82373,"size_after":68747},"zeen-900-900":{"time":0.23,"bytes":32302,"percent":18.79,"size_before":171888,"size_after":139586},"large":{"time":0.3,"bytes":23932,"percent":16.36,"size_before":146248,"size_after":122316},"post-thumbnail":{"time":0.62,"bytes":37075,"percent":18.26,"size_before":203019,"size_after":165944},"zeen-1400-full":{"time":0.89,"bytes":46582,"percent":18.39,"size_before":253369,"size_after":206787},"zeen-1170-585":{"time":0.37,"bytes":28905,"percent":17.52,"size_before":165008,"size_after":136103},"zeen-1500-750":{"time":0.35,"bytes":45054,"percent":17.86,"size_before":252258,"size_after":207204},"1536x1536":{"time":0.76,"bytes":56185,"percent":18.95,"size_before":296547,"size_after":240362},"zeen-770-full":{"time":0.17,"bytes":4250,"percent":5.35,"size_before":79470,"size_after":75220},"gform-image-choice-lg":{"time":0.2,"bytes":3579,"percent":4.78,"size_before":74912,"size_after":71333},"zeen-1155-770":{"time":0.44,"bytes":7827,"percent":4.5,"size_before":173771,"size_after":165944},"gform-image-choice-sm":{"time":0.26,"bytes":1351,"percent":5.8,"size_before":23312,"size_after":21961},"gform-image-choice-md":{"time":0.5,"bytes":1984,"percent":5.28,"size_before":37586,"size_after":35602}},"webp_flag":"2020\/04\/1995-Porsche-911-Speedster-993.jpg.webp"},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/04\/1995-Porsche-911-Speedster-993.jpg'><img decoding=\"async\" width=\"2000\" height=\"1127\" src=\"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/04\/1995-Porsche-911-Speedster-993.jpg\" class=\"attachment-medium size-full\" alt=\"\" srcset=\"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/04\/1995-Porsche-911-Speedster-993-300x169.jpg 300w, https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/04\/1995-Porsche-911-Speedster-993-1024x577.jpg 1024w, https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/04\/1995-Porsche-911-Speedster-993-100x56.jpg 100w, https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/04\/1995-Porsche-911-Speedster-993-770x434.jpg 770w, https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/04\/1995-Porsche-911-Speedster-993-1536x866.jpg 1536w, https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/04\/1995-Porsche-911-Speedster-993-293x165.jpg 293w, https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/04\/1995-Porsche-911-Speedster-993-1400x789.jpg 1400w, https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/04\/1995-Porsche-911-Speedster-993.jpg 2000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2000,"height":1127,"file":"2020\/04\/1995-Porsche-911-Speedster-993.jpg","filesize":294435,"sizes":{"medium":{"file":"1995-Porsche-911-Speedster-993-300x169.jpg","width":300,"height":169,"filesize":15125,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/04\/1995-Porsche-911-Speedster-993-300x169.jpg"},"large":{"file":"1995-Porsche-911-Speedster-993-1024x577.jpg","width":1024,"height":577,"filesize":128439,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/04\/1995-Porsche-911-Speedster-993-1024x577.jpg"},"thumbnail":{"file":"1995-Porsche-911-Speedster-993-100x56.jpg","width":100,"height":56,"filesize":2575,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/04\/1995-Porsche-911-Speedster-993-100x56.jpg"},"medium_large":{"file":"1995-Porsche-911-Speedster-993-770x434.jpg","width":770,"height":434,"filesize":79470,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/04\/1995-Porsche-911-Speedster-993-770x434.jpg"},"1536x1536":{"file":"1995-Porsche-911-Speedster-993-1536x866.jpg","width":1536,"height":866,"filesize":251364,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/04\/1995-Porsche-911-Speedster-993-1536x866.jpg"},"lets-review-360-240":{"file":"1995-Porsche-911-Speedster-993-360x240.jpg","width":360,"height":240,"filesize":23375,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/04\/1995-Porsche-911-Speedster-993-360x240.jpg"},"post-thumbnail":{"file":"1995-Porsche-911-Speedster-993-1155x770.jpg","width":1155,"height":770,"filesize":173771,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/04\/1995-Porsche-911-Speedster-993-1155x770.jpg"},"zeen-370-247":{"file":"1995-Porsche-911-Speedster-993-370x247.jpg","width":370,"height":247,"filesize":25088,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/04\/1995-Porsche-911-Speedster-993-370x247.jpg"},"zeen-585-293":{"file":"1995-Porsche-911-Speedster-993-585x293.jpg","width":585,"height":293,"filesize":44076,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/04\/1995-Porsche-911-Speedster-993-585x293.jpg"},"zeen-770-513":{"file":"1995-Porsche-911-Speedster-993-770x513.jpg","width":770,"height":513,"filesize":88753,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/04\/1995-Porsche-911-Speedster-993-770x513.jpg"},"zeen-1155-770":{"file":"1995-Porsche-911-Speedster-993-1155x770.jpg","width":1155,"height":770,"filesize":173771,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/04\/1995-Porsche-911-Speedster-993-1155x770.jpg"},"zeen-1170-585":{"file":"1995-Porsche-911-Speedster-993-1170x585.jpg","width":1170,"height":585,"filesize":142729,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/04\/1995-Porsche-911-Speedster-993-1170x585.jpg"},"zeen-1500-750":{"file":"1995-Porsche-911-Speedster-993-1500x750.jpg","width":1500,"height":750,"filesize":216593,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/04\/1995-Porsche-911-Speedster-993-1500x750.jpg"},"zeen-293-293":{"file":"1995-Porsche-911-Speedster-993-293x293.jpg","width":293,"height":293,"filesize":22302,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/04\/1995-Porsche-911-Speedster-993-293x293.jpg"},"zeen-390-390":{"file":"1995-Porsche-911-Speedster-993-390x390.jpg","width":390,"height":390,"filesize":36409,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/04\/1995-Porsche-911-Speedster-993-390x390.jpg"},"zeen-585-585":{"file":"1995-Porsche-911-Speedster-993-585x585.jpg","width":585,"height":585,"filesize":72222,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/04\/1995-Porsche-911-Speedster-993-585x585.jpg"},"zeen-900-900":{"file":"1995-Porsche-911-Speedster-993-900x900.jpg","width":900,"height":900,"filesize":145840,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/04\/1995-Porsche-911-Speedster-993-900x900.jpg"},"zeen-370-490":{"file":"1995-Porsche-911-Speedster-993-370x490.jpg","width":370,"height":490,"filesize":39053,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/04\/1995-Porsche-911-Speedster-993-370x490.jpg"},"zeen-585-775":{"file":"1995-Porsche-911-Speedster-993-585x775.jpg","width":585,"height":775,"filesize":83468,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/04\/1995-Porsche-911-Speedster-993-585x775.jpg"},"zeen-770-1020":{"file":"1995-Porsche-911-Speedster-993-770x1020.jpg","width":770,"height":1020,"filesize":129701,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/04\/1995-Porsche-911-Speedster-993-770x1020.jpg"},"zeen-293-full":{"file":"1995-Porsche-911-Speedster-993-293x165.jpg","width":293,"height":165,"filesize":14499,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/04\/1995-Porsche-911-Speedster-993-293x165.jpg"},"zeen-770-full":{"file":"1995-Porsche-911-Speedster-993-770x434.jpg","width":770,"height":434,"filesize":79470,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/04\/1995-Porsche-911-Speedster-993-770x434.jpg"},"zeen-1400-full":{"file":"1995-Porsche-911-Speedster-993-1400x789.jpg","width":1400,"height":789,"filesize":216566,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/04\/1995-Porsche-911-Speedster-993-1400x789.jpg"},"gform-image-choice-sm":{"file":"1995-Porsche-911-Speedster-993-300x300.jpg","width":300,"height":300,"filesize":23312,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/04\/1995-Porsche-911-Speedster-993-300x300.jpg"},"gform-image-choice-md":{"file":"1995-Porsche-911-Speedster-993-400x400.jpg","width":400,"height":400,"filesize":37586,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/04\/1995-Porsche-911-Speedster-993-400x400.jpg"},"gform-image-choice-lg":{"file":"1995-Porsche-911-Speedster-993-600x600.jpg","width":600,"height":600,"filesize":74912,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/04\/1995-Porsche-911-Speedster-993-600x600.jpg"},"full":{"file":"1995-Porsche-911-Speedster-993.jpg","width":2000,"height":1127,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/04\/1995-Porsche-911-Speedster-993.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":362375,"source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2020\/04\/1995-Porsche-911-Speedster-993.jpg","_links":{"self":[{"href":"https:\/\/www.supercars.net\/blog\/wp-json\/wp\/v2\/media\/362382","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.supercars.net\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.supercars.net\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.supercars.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.supercars.net\/blog\/wp-json\/wp\/v2\/comments?post=362382"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":362375,"href":"https:\/\/www.supercars.net\/blog\/wp-json\/wp\/v2\/posts\/362375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}