{"id":6168,"date":"2016-01-07T03:18:02","date_gmt":"2016-01-07T03:18:02","guid":{"rendered":"http:\/\/blog.supercars.net\/blog\/wp-content\/uploads\/2016\/01\/autowp.ru_koenigsegg_ccx_uk-spec_10.jpg"},"modified":"2016-01-07T03:18:54","modified_gmt":"2016-01-07T03:18:54","slug":"autowp-ru_koenigsegg_ccx_uk-spec_10","status":"inherit","type":"attachment","link":"https:\/\/www.supercars.net\/blog\/2006-koenigsegg-ccx-gallery\/autowp-ru_koenigsegg_ccx_uk-spec_10\/","title":{"rendered":"Koenigsegg CCX"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-6168","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Koenigsegg CCX | | SuperCars.net<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/01\/autowp.ru_koenigsegg_ccx_uk-spec_10.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Koenigsegg CCX | | SuperCars.net\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/01\/autowp.ru_koenigsegg_ccx_uk-spec_10.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Supercars.net\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Supercars.net\/\" \/>\n<meta property=\"article:modified_time\" content=\"2016-01-07T03:18:54+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/01\/autowp.ru_koenigsegg_ccx_uk-spec_10.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@supercars_net\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.supercars.net\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/autowp.ru_koenigsegg_ccx_uk-spec_10.jpg\",\"url\":\"http:\\\/\\\/www.supercars.net\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/autowp.ru_koenigsegg_ccx_uk-spec_10.jpg\",\"name\":\"Koenigsegg CCX | | SuperCars.net\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/#website\"},\"datePublished\":\"2016-01-07T03:18:02+00:00\",\"dateModified\":\"2016-01-07T03:18:54+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.supercars.net\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/autowp.ru_koenigsegg_ccx_uk-spec_10.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.supercars.net\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/autowp.ru_koenigsegg_ccx_uk-spec_10.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.supercars.net\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/autowp.ru_koenigsegg_ccx_uk-spec_10.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"2006 Koenigsegg CCX Image Gallery\",\"item\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/2006-koenigsegg-ccx-gallery\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Koenigsegg CCX\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/\",\"name\":\"Supercars.net\",\"description\":\"Exotic and Supercar news, information, pictures and videos\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Koenigsegg CCX | | SuperCars.net","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/01\/autowp.ru_koenigsegg_ccx_uk-spec_10.jpg","og_locale":"en_US","og_type":"article","og_title":"Koenigsegg CCX | | SuperCars.net","og_url":"http:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/01\/autowp.ru_koenigsegg_ccx_uk-spec_10.jpg","og_site_name":"Supercars.net","article_publisher":"https:\/\/www.facebook.com\/Supercars.net\/","article_modified_time":"2016-01-07T03:18:54+00:00","og_image":[{"width":2048,"height":1536,"url":"http:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/01\/autowp.ru_koenigsegg_ccx_uk-spec_10.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@supercars_net","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/01\/autowp.ru_koenigsegg_ccx_uk-spec_10.jpg","url":"http:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/01\/autowp.ru_koenigsegg_ccx_uk-spec_10.jpg","name":"Koenigsegg CCX | | SuperCars.net","isPartOf":{"@id":"https:\/\/www.supercars.net\/blog\/#website"},"datePublished":"2016-01-07T03:18:02+00:00","dateModified":"2016-01-07T03:18:54+00:00","breadcrumb":{"@id":"http:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/01\/autowp.ru_koenigsegg_ccx_uk-spec_10.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/01\/autowp.ru_koenigsegg_ccx_uk-spec_10.jpg"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/01\/autowp.ru_koenigsegg_ccx_uk-spec_10.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.supercars.net\/blog\/"},{"@type":"ListItem","position":2,"name":"2006 Koenigsegg CCX Image Gallery","item":"https:\/\/www.supercars.net\/blog\/2006-koenigsegg-ccx-gallery\/"},{"@type":"ListItem","position":3,"name":"Koenigsegg CCX"}]},{"@type":"WebSite","@id":"https:\/\/www.supercars.net\/blog\/#website","url":"https:\/\/www.supercars.net\/blog\/","name":"Supercars.net","description":"Exotic and Supercar news, information, pictures and videos","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.supercars.net\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"smush":{"stats":{"percent":14.97008373927946,"bytes":319355,"size_before":2133288,"size_after":1813933,"time":2.3899999999999997,"api_version":"1.0","lossy":true,"keep_exif":0},"sizes":{"zeen-370-247":{"percent":12.04,"bytes":2251,"size_before":18703,"size_after":16452,"time":0.03},"zeen-293-full":{"percent":11.71,"bytes":1588,"size_before":13559,"size_after":11971,"time":0.02},"thumbnail":{"percent":2.83,"bytes":71,"size_before":2505,"size_after":2434,"time":0.03},"lets-review-360-240":{"percent":12.22,"bytes":2164,"size_before":17703,"size_after":15539,"time":0.03},"medium":{"percent":11.82,"bytes":1676,"size_before":14177,"size_after":12501,"time":0.03},"zeen-585-293":{"percent":11.42,"bytes":3767,"size_before":32984,"size_after":29217,"time":0.05},"zeen-370-490":{"percent":14.04,"bytes":5249,"size_before":37392,"size_after":32143,"time":0.03},"zeen-390-390":{"percent":13.39,"bytes":4204,"size_before":31399,"size_after":27195,"time":0.04},"zeen-293-293":{"percent":12.85,"bytes":2411,"size_before":18764,"size_after":16353,"time":0.06},"medium_large":{"percent":14.05,"bytes":11572,"size_before":82340,"size_after":70768,"time":0.08},"zeen-585-585":{"percent":14.78,"bytes":10135,"size_before":68588,"size_after":58453,"time":0.1},"large":{"percent":14.64,"bytes":21203,"size_before":144869,"size_after":123666,"time":0.1},"zeen-770-1020":{"percent":16.96,"bytes":27629,"size_before":162894,"size_after":135265,"time":0.11},"post-thumbnail":{"percent":14.77,"bytes":25681,"size_before":173927,"size_after":148246,"time":0.12},"zeen-1170-585":{"percent":13.16,"bytes":16857,"size_before":128119,"size_after":111262,"time":0.13},"zeen-770-513":{"percent":14.04,"bytes":10484,"size_before":74661,"size_after":64177,"time":0.15},"zeen-585-775":{"percent":15.58,"bytes":14479,"size_before":92923,"size_after":78444,"time":0.19},"zeen-900-900":{"percent":15.85,"bytes":26270,"size_before":165763,"size_after":139493,"time":0.22},"zeen-1500-750":{"percent":13.84,"bytes":29276,"size_before":211585,"size_after":182309,"time":0.26},"1536x1536":{"percent":16.27,"bytes":56947,"size_before":349984,"size_after":293037,"time":0.29},"zeen-1400-full":{"percent":15.65,"bytes":45441,"size_before":290449,"size_after":245008,"time":0.32}}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/01\/autowp.ru_koenigsegg_ccx_uk-spec_10.jpg'><img decoding=\"async\" width=\"2048\" height=\"1536\" src=\"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/01\/autowp.ru_koenigsegg_ccx_uk-spec_10.jpg\" class=\"attachment-medium size-full\" alt=\"\" srcset=\"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/01\/autowp.ru_koenigsegg_ccx_uk-spec_10-300x225.jpg 300w, https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/01\/autowp.ru_koenigsegg_ccx_uk-spec_10-1024x768.jpg 1024w, https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/01\/autowp.ru_koenigsegg_ccx_uk-spec_10-100x75.jpg 100w, https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/01\/autowp.ru_koenigsegg_ccx_uk-spec_10-770x578.jpg 770w, https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/01\/autowp.ru_koenigsegg_ccx_uk-spec_10-1536x1152.jpg 1536w, https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/01\/autowp.ru_koenigsegg_ccx_uk-spec_10-293x220.jpg 293w, https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/01\/autowp.ru_koenigsegg_ccx_uk-spec_10-1400x1050.jpg 1400w, https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/01\/autowp.ru_koenigsegg_ccx_uk-spec_10.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2048,"height":1536,"file":"2016\/01\/autowp.ru_koenigsegg_ccx_uk-spec_10.jpg","sizes":{"medium":{"file":"autowp.ru_koenigsegg_ccx_uk-spec_10-300x225.jpg","width":300,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/01\/autowp.ru_koenigsegg_ccx_uk-spec_10-300x225.jpg"},"large":{"file":"autowp.ru_koenigsegg_ccx_uk-spec_10-1024x768.jpg","width":1024,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/01\/autowp.ru_koenigsegg_ccx_uk-spec_10-1024x768.jpg"},"thumbnail":{"file":"autowp.ru_koenigsegg_ccx_uk-spec_10-100x75.jpg","width":100,"height":75,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/01\/autowp.ru_koenigsegg_ccx_uk-spec_10-100x75.jpg"},"medium_large":{"file":"autowp.ru_koenigsegg_ccx_uk-spec_10-770x578.jpg","width":770,"height":578,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/01\/autowp.ru_koenigsegg_ccx_uk-spec_10-770x578.jpg"},"1536x1536":{"file":"autowp.ru_koenigsegg_ccx_uk-spec_10-1536x1152.jpg","width":1536,"height":1152,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/01\/autowp.ru_koenigsegg_ccx_uk-spec_10-1536x1152.jpg"},"lets-review-360-240":{"file":"autowp.ru_koenigsegg_ccx_uk-spec_10-360x240.jpg","width":360,"height":240,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/01\/autowp.ru_koenigsegg_ccx_uk-spec_10-360x240.jpg"},"post-thumbnail":{"file":"autowp.ru_koenigsegg_ccx_uk-spec_10-1155x770.jpg","width":1155,"height":770,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/01\/autowp.ru_koenigsegg_ccx_uk-spec_10-1155x770.jpg"},"zeen-370-247":{"file":"autowp.ru_koenigsegg_ccx_uk-spec_10-370x247.jpg","width":370,"height":247,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/01\/autowp.ru_koenigsegg_ccx_uk-spec_10-370x247.jpg"},"zeen-585-293":{"file":"autowp.ru_koenigsegg_ccx_uk-spec_10-585x293.jpg","width":585,"height":293,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/01\/autowp.ru_koenigsegg_ccx_uk-spec_10-585x293.jpg"},"zeen-770-513":{"file":"autowp.ru_koenigsegg_ccx_uk-spec_10-770x513.jpg","width":770,"height":513,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/01\/autowp.ru_koenigsegg_ccx_uk-spec_10-770x513.jpg"},"zeen-1155-770":{"file":"autowp.ru_koenigsegg_ccx_uk-spec_10-1155x770.jpg","width":1155,"height":770,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/01\/autowp.ru_koenigsegg_ccx_uk-spec_10-1155x770.jpg"},"zeen-1170-585":{"file":"autowp.ru_koenigsegg_ccx_uk-spec_10-1170x585.jpg","width":1170,"height":585,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/01\/autowp.ru_koenigsegg_ccx_uk-spec_10-1170x585.jpg"},"zeen-1500-750":{"file":"autowp.ru_koenigsegg_ccx_uk-spec_10-1500x750.jpg","width":1500,"height":750,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/01\/autowp.ru_koenigsegg_ccx_uk-spec_10-1500x750.jpg"},"zeen-293-293":{"file":"autowp.ru_koenigsegg_ccx_uk-spec_10-293x293.jpg","width":293,"height":293,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/01\/autowp.ru_koenigsegg_ccx_uk-spec_10-293x293.jpg"},"zeen-390-390":{"file":"autowp.ru_koenigsegg_ccx_uk-spec_10-390x390.jpg","width":390,"height":390,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/01\/autowp.ru_koenigsegg_ccx_uk-spec_10-390x390.jpg"},"zeen-585-585":{"file":"autowp.ru_koenigsegg_ccx_uk-spec_10-585x585.jpg","width":585,"height":585,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/01\/autowp.ru_koenigsegg_ccx_uk-spec_10-585x585.jpg"},"zeen-900-900":{"file":"autowp.ru_koenigsegg_ccx_uk-spec_10-900x900.jpg","width":900,"height":900,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/01\/autowp.ru_koenigsegg_ccx_uk-spec_10-900x900.jpg"},"zeen-370-490":{"file":"autowp.ru_koenigsegg_ccx_uk-spec_10-370x490.jpg","width":370,"height":490,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/01\/autowp.ru_koenigsegg_ccx_uk-spec_10-370x490.jpg"},"zeen-585-775":{"file":"autowp.ru_koenigsegg_ccx_uk-spec_10-585x775.jpg","width":585,"height":775,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/01\/autowp.ru_koenigsegg_ccx_uk-spec_10-585x775.jpg"},"zeen-770-1020":{"file":"autowp.ru_koenigsegg_ccx_uk-spec_10-770x1020.jpg","width":770,"height":1020,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/01\/autowp.ru_koenigsegg_ccx_uk-spec_10-770x1020.jpg"},"zeen-293-full":{"file":"autowp.ru_koenigsegg_ccx_uk-spec_10-293x220.jpg","width":293,"height":220,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/01\/autowp.ru_koenigsegg_ccx_uk-spec_10-293x220.jpg"},"zeen-770-full":{"file":"autowp.ru_koenigsegg_ccx_uk-spec_10-770x578.jpg","width":770,"height":578,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/01\/autowp.ru_koenigsegg_ccx_uk-spec_10-770x578.jpg"},"zeen-1400-full":{"file":"autowp.ru_koenigsegg_ccx_uk-spec_10-1400x1050.jpg","width":1400,"height":1050,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/01\/autowp.ru_koenigsegg_ccx_uk-spec_10-1400x1050.jpg"},"full":{"file":"autowp.ru_koenigsegg_ccx_uk-spec_10.jpg","width":2048,"height":1536,"mime_type":"image\/jpeg","source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/01\/autowp.ru_koenigsegg_ccx_uk-spec_10.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":6107,"source_url":"https:\/\/www.supercars.net\/blog\/wp-content\/uploads\/2016\/01\/autowp.ru_koenigsegg_ccx_uk-spec_10.jpg","filename":"autowp.ru_koenigsegg_ccx_uk-spec_10.jpg","filesize":1520763,"_links":{"self":[{"href":"https:\/\/www.supercars.net\/blog\/wp-json\/wp\/v2\/media\/6168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.supercars.net\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.supercars.net\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.supercars.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.supercars.net\/blog\/wp-json\/wp\/v2\/comments?post=6168"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":6107,"href":"https:\/\/www.supercars.net\/blog\/wp-json\/wp\/v2\/posts\/6107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}