{"id":1486,"count":9,"description":"","link":"https:\/\/www.supercars.net\/blog\/tag\/dodge-coronet\/","name":"Dodge Coronet","slug":"dodge-coronet","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dodge Coronet Archives - Supercars.net<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.supercars.net\/blog\/tag\/dodge-coronet\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dodge Coronet Archives - Supercars.net\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.supercars.net\/blog\/tag\/dodge-coronet\/\" \/>\n<meta property=\"og:site_name\" content=\"Supercars.net\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@supercars_net\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/tag\\\/dodge-coronet\\\/\",\"url\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/tag\\\/dodge-coronet\\\/\",\"name\":\"Dodge Coronet Archives - Supercars.net\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/tag\\\/dodge-coronet\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/tag\\\/dodge-coronet\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dodge Coronet\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/\",\"name\":\"Supercars.net\",\"description\":\"Exotic and Supercar news, information, pictures and videos\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.supercars.net\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dodge Coronet Archives - Supercars.net","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.supercars.net\/blog\/tag\/dodge-coronet\/","og_locale":"en_US","og_type":"article","og_title":"Dodge Coronet Archives - Supercars.net","og_url":"https:\/\/www.supercars.net\/blog\/tag\/dodge-coronet\/","og_site_name":"Supercars.net","twitter_card":"summary_large_image","twitter_site":"@supercars_net","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.supercars.net\/blog\/tag\/dodge-coronet\/","url":"https:\/\/www.supercars.net\/blog\/tag\/dodge-coronet\/","name":"Dodge Coronet Archives - Supercars.net","isPartOf":{"@id":"https:\/\/www.supercars.net\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.supercars.net\/blog\/tag\/dodge-coronet\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.supercars.net\/blog\/tag\/dodge-coronet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.supercars.net\/blog\/"},{"@type":"ListItem","position":2,"name":"Dodge Coronet"}]},{"@type":"WebSite","@id":"https:\/\/www.supercars.net\/blog\/#website","url":"https:\/\/www.supercars.net\/blog\/","name":"Supercars.net","description":"Exotic and Supercar news, information, pictures and videos","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.supercars.net\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.supercars.net\/blog\/wp-json\/wp\/v2\/tags\/1486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.supercars.net\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.supercars.net\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.supercars.net\/blog\/wp-json\/wp\/v2\/posts?tags=1486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}